{"id":19421,"date":"2019-12-14T02:11:15","date_gmt":"2019-12-14T01:11:15","guid":{"rendered":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/?p=19421"},"modified":"2019-12-14T02:11:32","modified_gmt":"2019-12-14T01:11:32","slug":"green-new-deal-der-euro-oekopranger-achgut-com","status":"publish","type":"post","link":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/2019\/12\/14\/green-new-deal-der-euro-oekopranger-achgut-com\/","title":{"rendered":"\u201eGreen New Deal\u201d: Der Euro-\u00d6kopranger | achgut.com"},"content":{"rendered":"<p>Von Carl Christian Jancke | Die Achse des Guten<\/p>\n<p>Leseprobe:<br \/>\n(&#8230;) <strong>Ursula von der Leyen will im Rahmen des Green New Deals eine Taxonomie anlegen, berichtet\u00a0<a href=\"https:\/\/www.gaborsteingart.com\/newsletter-morning-briefing\/investitionslenkung-in-europa\/?wp-nocache=true\" target=\"_blank\" rel=\"noopener noreferrer\">Gabor Steingart<\/a>\u00a0in seinem Morning Briefing. In einer White- and Blacklist werden klimafreundliche und -sch\u00e4dliche Unternehmen unterteilt. Wer nicht spurt, dem soll der Zugang zum Kapitalmarkt verwehrt werden.\u00a0<\/strong><\/p>\n<p>Daf\u00fcr sorgt auch die Europ\u00e4ische Zentralbank, die mit Greenwashing hofft, ihre desastr\u00f6se Geldpolitik zu kaschieren. Ab sofort druckt sie das Scheingeld zur Rettung des Weltklimas und nicht nur des Euros. Davon geht anscheinend keine Gefahr aus \u2013 weil es ja nur elektronisch entsteht, kann man es nicht verbrennen ;-).<\/p>\n<p><a href=\"https:\/\/www.achgut.com\/artikel\/green_new_deal_von_der_euro_oekopranger\" target=\"_blank\" rel=\"noopener noreferrer\">Alles lesen bei achgut.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Carl Christian Jancke | Die Achse des Guten Leseprobe: (&#8230;) Ursula von der Leyen will im Rahmen des Green New Deals eine Taxonomie anlegen, berichtet\u00a0Gabor Steingart\u00a0in seinem Morning Briefing. In einer White- and Blacklist werden klimafreundliche und -sch\u00e4dliche Unternehmen unterteilt. Wer nicht spurt, dem soll der Zugang zum Kapitalmarkt verwehrt werden.\u00a0 Daf\u00fcr sorgt auch &hellip; <a href=\"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/2019\/12\/14\/green-new-deal-der-euro-oekopranger-achgut-com\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e\u201eGreen New Deal\u201d: Der Euro-\u00d6kopranger | achgut.com\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[457],"tags":[240,495,446,299,251],"class_list":["post-19421","post","type-post","status-publish","format-standard","hentry","category-klimapolitik","tag-eu","tag-green-deal","tag-klimadiktatur","tag-klimapolitik","tag-planwirtschaft"],"_links":{"self":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/19421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=19421"}],"version-history":[{"count":1,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/19421\/revisions"}],"predecessor-version":[{"id":19422,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/19421\/revisions\/19422"}],"wp:attachment":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=19421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=19421"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=19421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}