{"id":28613,"date":"2021-10-20T03:46:31","date_gmt":"2021-10-20T01:46:31","guid":{"rendered":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/?p=28613"},"modified":"2021-10-20T03:47:48","modified_gmt":"2021-10-20T01:47:48","slug":"klimarettung-und-energiekrise-ein-ueberblick-eike","status":"publish","type":"post","link":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/2021\/10\/20\/klimarettung-und-energiekrise-ein-ueberblick-eike\/","title":{"rendered":"Klimarettung und Energiekrise: ein \u00dcberblick | EIKE"},"content":{"rendered":"<blockquote><p><span style=\"font-size: 12pt;\"><strong>Die Hiobsbotschaften, auch in den Massenmedien, sie rei\u00dfen nicht ab: Nicht nur die Rohstoffe wie Eisen werden knapp, sondern auch das Erdgas \u2013 und zwar in ganz Europa. Das liegt nicht nur an russischer und chinesischer Politik, sondern in erster Linie an der EU-Klimapolitik, die in erster Linie deutscher Herkunft ist.<\/strong><\/span><\/p><\/blockquote>\n<p>Weiterlesen: <em><a href=\"https:\/\/eike-klima-energie.eu\/2021\/10\/19\/klimarettung-und-energiekrise-ein-ueberblick\/\" target=\"_blank\" rel=\"noopener noreferrer\">Klimarettung und Energiekrise: ein \u00dcberblick | EIKE &#8211; Europ\u00e4isches Institut f\u00fcr Klima &amp; Energie<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Hiobsbotschaften, auch in den Massenmedien, sie rei\u00dfen nicht ab: Nicht nur die Rohstoffe wie Eisen werden knapp, sondern auch das Erdgas \u2013 und zwar in ganz Europa. Das liegt nicht nur an russischer und chinesischer Politik, sondern in erster Linie an der EU-Klimapolitik, die in erster Linie deutscher Herkunft ist. Weiterlesen: Klimarettung und Energiekrise: &hellip; <a href=\"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/2021\/10\/20\/klimarettung-und-energiekrise-ein-ueberblick-eike\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eKlimarettung und Energiekrise: ein \u00dcberblick | EIKE\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[457],"tags":[633,240,299],"class_list":["post-28613","post","type-post","status-publish","format-standard","hentry","category-klimapolitik","tag-energiekrise","tag-eu","tag-klimapolitik"],"_links":{"self":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/28613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=28613"}],"version-history":[{"count":3,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/28613\/revisions"}],"predecessor-version":[{"id":28616,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/28613\/revisions\/28616"}],"wp:attachment":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=28613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=28613"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=28613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}