{"id":30198,"date":"2021-12-28T04:31:22","date_gmt":"2021-12-28T03:31:22","guid":{"rendered":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/?p=30198"},"modified":"2021-12-28T04:32:29","modified_gmt":"2021-12-28T03:32:29","slug":"wie-vw-sich-still-von-der-reinen-elektrostrategie-verabschiedet-te","status":"publish","type":"post","link":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/2021\/12\/28\/wie-vw-sich-still-von-der-reinen-elektrostrategie-verabschiedet-te\/","title":{"rendered":"Wie VW sich still von der reinen Elektrostrategie verabschiedet | TE"},"content":{"rendered":"<blockquote><p><span style=\"font-size: 12pt;\"><strong>Wenn es um heikle Themen geht, beherrscht Volkswagen die Kunst der Tarnung vor \u00f6ffentlicher Aufmerksamkeit. Wie zum Beispiel bei der Abkehr von der bisherigen Antriebsstrategie ausschlie\u00dflich auf Elektrobasis \u2013 zugunsten neuer Verbrennermotoren.<\/strong><\/span><\/p><\/blockquote>\n<blockquote class=\"wp-embedded-content\" data-secret=\"ZHRwTRW4Z3\"><p><a href=\"https:\/\/www.tichyseinblick.de\/wirtschaft\/wie-vw-sich-heimlich-von-der-reinen-elektrostrategie-verabschiedet\/\">Wie VW sich still von der reinen Elektrostrategie verabschiedet<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" src=\"https:\/\/www.tichyseinblick.de\/wirtschaft\/wie-vw-sich-heimlich-von-der-reinen-elektrostrategie-verabschiedet\/embed\/#?secret=ZHRwTRW4Z3\" data-secret=\"ZHRwTRW4Z3\" width=\"600\" height=\"338\" title=\"&#8222;Wie VW sich still von der reinen Elektrostrategie verabschiedet&#8220; &#8212; Tichys Einblick\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>Weiterlesen: <em><a href=\"https:\/\/www.tichyseinblick.de\/wirtschaft\/wie-vw-sich-heimlich-von-der-reinen-elektrostrategie-verabschiedet\/\" target=\"_blank\" rel=\"noopener noreferrer\">Wie VW sich still von der reinen Elektrostrategie verabschiedet<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn es um heikle Themen geht, beherrscht Volkswagen die Kunst der Tarnung vor \u00f6ffentlicher Aufmerksamkeit. Wie zum Beispiel bei der Abkehr von der bisherigen Antriebsstrategie ausschlie\u00dflich auf Elektrobasis \u2013 zugunsten neuer Verbrennermotoren. Wie VW sich still von der reinen Elektrostrategie verabschiedet Weiterlesen: Wie VW sich still von der reinen Elektrostrategie verabschiedet<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[208],"class_list":["post-30198","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-e-mobilitaet"],"_links":{"self":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/30198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=30198"}],"version-history":[{"count":2,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/30198\/revisions"}],"predecessor-version":[{"id":30200,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/30198\/revisions\/30200"}],"wp:attachment":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=30198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=30198"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=30198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}