{"id":30201,"date":"2021-12-28T04:34:57","date_gmt":"2021-12-28T03:34:57","guid":{"rendered":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/?p=30201"},"modified":"2021-12-28T04:38:32","modified_gmt":"2021-12-28T03:38:32","slug":"politische-wissenschaft-liefert-erwartete-ergebnisse-te-wecker-am-27-dezember-2021","status":"publish","type":"post","link":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/2021\/12\/28\/politische-wissenschaft-liefert-erwartete-ergebnisse-te-wecker-am-27-dezember-2021\/","title":{"rendered":"Politische Wissenschaft liefert erwartete Ergebnisse &#8211; TE Wecker am 27. Dezember 2021"},"content":{"rendered":"<blockquote><p><span style=\"font-size: 12pt;\"><strong>In dieser Woche \u201eTE Weihnachtswecker\u201c ++ Heute: Kritik an Ethikkommission zum Atomausstieg: Vereinnahmung durch die Regierung ++ Zum Ende dieses Jahres werden unter anderem drei weitere Kernkraftwerke abgeschaltet. Die Grundlagen dazu wurden bereits vor zehn Jahren gelegt. Eine Ethikkommission lieferte die Rechtfertigung. Gespr\u00e4ch mit Prof Andr\u00e9 Thess: Leitbild unabh\u00e4ngiger Wissenschaft nicht gerecht geworden ++<\/strong><\/span><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/1185271966&amp;color=%23ff5500&amp;auto_play=false&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true&amp;visual=true\" width=\"100%\" height=\"300\" frameborder=\"no\" scrolling=\"no\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<div style=\"font-size: 10px; color: #cccccc; line-break: anywhere; word-break: normal; overflow: hidden; white-space: nowrap; text-overflow: ellipsis; font-family: Interstate,Lucida Grande,Lucida Sans Unicode,Lucida Sans,Garuda,Verdana,Tahoma,sans-serif; font-weight: 100;\"><a style=\"color: #cccccc; text-decoration: none;\" title=\"Tichys Einblick\" href=\"https:\/\/soundcloud.com\/tichys-einblick\" target=\"_blank\" rel=\"noopener noreferrer\">Tichys Einblick<\/a> \u00b7 <a style=\"color: #cccccc; text-decoration: none;\" title=\"TE Wecker am 27.12.2021\" href=\"https:\/\/soundcloud.com\/tichys-einblick\/te-wecker-27122021\" target=\"_blank\" rel=\"noopener noreferrer\">TE Wecker am 27.12.2021<\/a><\/div>\n<p>Quelle: <em><a href=\"https:\/\/www.tichyseinblick.de\/podcast\/te-wecker-am-27-dezember-2021\/?fbclid=IwAR3L9IUpUraMH3ejaY2MSE_5OtTklKkx91LxmR7vP6YE_ZKPHpvP4ARqO6w\" target=\"_blank\" rel=\"noopener noreferrer\">Politische Wissenschaft liefert erwartete Ergebnisse &#8211; TE Wecker am 27. Dezember 2021<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In dieser Woche \u201eTE Weihnachtswecker\u201c ++ Heute: Kritik an Ethikkommission zum Atomausstieg: Vereinnahmung durch die Regierung ++ Zum Ende dieses Jahres werden unter anderem drei weitere Kernkraftwerke abgeschaltet. Die Grundlagen dazu wurden bereits vor zehn Jahren gelegt. Eine Ethikkommission lieferte die Rechtfertigung. Gespr\u00e4ch mit Prof Andr\u00e9 Thess: Leitbild unabh\u00e4ngiger Wissenschaft nicht gerecht geworden ++ Tichys &hellip; <a href=\"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/2021\/12\/28\/politische-wissenschaft-liefert-erwartete-ergebnisse-te-wecker-am-27-dezember-2021\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201ePolitische Wissenschaft liefert erwartete Ergebnisse &#8211; TE Wecker am 27. Dezember 2021\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[142,175,17],"class_list":["post-30201","post","type-post","status-publish","format-standard","hentry","category-energiepolitik","tag-atomausstieg","tag-energiepolitik","tag-energiewende"],"_links":{"self":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/30201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=30201"}],"version-history":[{"count":3,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/30201\/revisions"}],"predecessor-version":[{"id":30204,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/30201\/revisions\/30204"}],"wp:attachment":[{"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=30201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=30201"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=30201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}