{"id":35278,"date":"2022-10-10T04:25:53","date_gmt":"2022-10-10T02:25:53","guid":{"rendered":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/?p=35278"},"modified":"2022-10-10T04:26:22","modified_gmt":"2022-10-10T02:26:22","slug":"vince-ebert-wind-und-sonne-sind-einfach-nicht-grundlastfaehig-westfalen-blatt","status":"publish","type":"post","link":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/2022\/10\/10\/vince-ebert-wind-und-sonne-sind-einfach-nicht-grundlastfaehig-westfalen-blatt\/","title":{"rendered":"Vince Ebert: \u201eWind und Sonne sind einfach nicht grundlastf\u00e4hig\u201c | Westfalen-Blatt"},"content":{"rendered":"<blockquote><p><span style=\"font-size: 12pt;\"><strong>Vince Ebert (54) ist der Erfinder des Wissenschaftskabaretts. Seit seinem Programm \u201eUrknaller \u2013 Physik ist sexy\u201c und den Auftritten bei \u201eWissen vor acht\u201c im Ersten z\u00e4hlt er zu den Besten in der unterhaltenden Erkenntnisvermittlung. In seinem neuen Buch \u201eLichtblick statt Blackout\u201c nimmt er sich die sogenannte Energiewende vor.<\/strong><\/span><\/p><\/blockquote>\n<p>Ein Interview von Andreas Schnadwinkel<\/p>\n<p>Weiterlesen: <em><a href=\"https:\/\/www.westfalen-blatt.de\/owl\/vince-ebert-wind-und-sonne-sind-einfach-nicht-grundlastfahig-2641133?fbclid=IwAR1LaqlnwPrclx1ZEWFZqVtAhFmwfB3VCFocUOMQvqbiZFDvUKnExtHigrQ\" target=\"_blank\" rel=\"noopener noreferrer\">Vince Ebert: \u201eWind und Sonne sind einfach nicht grundlastf\u00e4hig\u201c<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vince Ebert (54) ist der Erfinder des Wissenschaftskabaretts. Seit seinem Programm \u201eUrknaller \u2013 Physik ist sexy\u201c und den Auftritten bei \u201eWissen vor acht\u201c im Ersten z\u00e4hlt er zu den Besten in der unterhaltenden Erkenntnisvermittlung. In seinem neuen Buch \u201eLichtblick statt Blackout\u201c nimmt er sich die sogenannte Energiewende vor. Ein Interview von Andreas Schnadwinkel Weiterlesen: Vince &hellip; <a href=\"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/2022\/10\/10\/vince-ebert-wind-und-sonne-sind-einfach-nicht-grundlastfaehig-westfalen-blatt\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eVince Ebert: \u201eWind und Sonne sind einfach nicht grundlastf\u00e4hig\u201c | Westfalen-Blatt\u201c<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[175,17],"class_list":["post-35278","post","type-post","status-publish","format-standard","hentry","category-energiepolitik","tag-energiepolitik","tag-energiewende"],"_links":{"self":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/35278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=35278"}],"version-history":[{"count":2,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/35278\/revisions"}],"predecessor-version":[{"id":35280,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/35278\/revisions\/35280"}],"wp:attachment":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=35278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=35278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=35278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}