{"id":36223,"date":"2023-01-10T19:33:04","date_gmt":"2023-01-10T18:33:04","guid":{"rendered":"http:\/\/www.vernunftkraft-hessen.de\/wordpress\/?p=36223"},"modified":"2023-01-10T19:33:35","modified_gmt":"2023-01-10T18:33:35","slug":"energiewende-warum-die-plaene-der-politik-selbstbetrug-sind-welt","status":"publish","type":"post","link":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/2023\/01\/10\/energiewende-warum-die-plaene-der-politik-selbstbetrug-sind-welt\/","title":{"rendered":"Energiewende: Warum die Pl\u00e4ne der Politik Selbstbetrug sind &#8211; WELT"},"content":{"rendered":"<blockquote><p><span style=\"font-size: 12pt;\"><strong>Die Realit\u00e4tsverweigerung in der deutschen Energiewende-Strategie erreicht bedenkliche Ausma\u00dfe. Als Reaktion auf einen Erdbeben-Tsunami in Japan hat die Bundesregierung zun\u00e4chst beschlossen, aus der Kernenergie auszusteigen. Und weil Russland auch nach 2014 noch als verl\u00e4sslicher Partner sch\u00f6ngeredet wurde, machte man sich von dessen Gas abh\u00e4ngig.<\/strong><\/span><\/p><\/blockquote>\n<p>Weiterlesen: <em><a href=\"https:\/\/www.welt.de\/wirtschaft\/article243031315\/Energiewende-Warum-die-Plaene-der-Politik-Selbstbetrug-sind.html\" target=\"_blank\" rel=\"noopener noreferrer\">Energiewende: Warum die Pl\u00e4ne der Politik Selbstbetrug sind &#8211; WELT<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Realit\u00e4tsverweigerung in der deutschen Energiewende-Strategie erreicht bedenkliche Ausma\u00dfe. Als Reaktion auf einen Erdbeben-Tsunami in Japan hat die Bundesregierung zun\u00e4chst beschlossen, aus der Kernenergie auszusteigen. Und weil Russland auch nach 2014 noch als verl\u00e4sslicher Partner sch\u00f6ngeredet wurde, machte man sich von dessen Gas abh\u00e4ngig. Weiterlesen: Energiewende: Warum die Pl\u00e4ne der Politik Selbstbetrug sind &#8211; WELT<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[222],"tags":[175,17],"class_list":["post-36223","post","type-post","status-publish","format-standard","hentry","category-energiepolitik","tag-energiepolitik","tag-energiewende"],"_links":{"self":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/36223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/comments?post=36223"}],"version-history":[{"count":2,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/36223\/revisions"}],"predecessor-version":[{"id":36225,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/posts\/36223\/revisions\/36225"}],"wp:attachment":[{"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=36223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/categories?post=36223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vernunftkraft-hessen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=36223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}